{"id":757,"date":"2023-02-13T01:36:52","date_gmt":"2023-02-13T01:36:52","guid":{"rendered":"https:\/\/sprocketgear.top\/china-custom-teeth-finished-bore-stainless-steel-idler-taper-transmission-differential-drive-gear-wheel-roller-chain-and-sprockets-sprocket-auto\/"},"modified":"2023-02-13T01:36:52","modified_gmt":"2023-02-13T01:36:52","slug":"china-custom-teeth-finished-bore-stainless-steel-idler-taper-transmission-differential-drive-gear-wheel-roller-chain-and-sprockets-sprocket-auto","status":"publish","type":"post","link":"https:\/\/sprocketgear.top\/es\/china-custom-teeth-finished-bore-stainless-steel-idler-taper-transmission-differential-drive-gear-wheel-roller-chain-and-sprockets-sprocket-auto\/","title":{"rendered":"Engranaje de transmisi\u00f3n diferencial c\u00f3nico de acero inoxidable con dientes personalizados de China, cadena de rodillos y ruedas dentadas, rueda dentada autom\u00e1tica"},"content":{"rendered":"<p>Industrias aplicables: puntos de venta de materiales de construcci\u00f3n, plantas de producci\u00f3n, minoristas de reparaci\u00f3n de equipos, obras de construcci\u00f3n, energ\u00eda y miner\u00eda<br \/>Sustancia: Metal<br \/>Regular: ISO<br \/>Identificaci\u00f3n del producto: Pi\u00f1\u00f3n de cadena<br \/>Software: Equipos de transmisi\u00f3n<br \/>Tratamiento del \u00e1rea: Galvanizado<br \/>Especificaciones del embalaje: 1. Normalmente, se utiliza embalaje neutro en el interior y embalaje de madera en el exterior. 2. Seg\u00fan las necesidades del cliente. 3. Puerto de carga: HangZhou, ZheJiang u otros puertos seg\u00fan las necesidades del cliente.<br \/>Puerto: Puerto de HangZhou, Puerto de ZheJiang u otros puertos seg\u00fan la necesidad del cliente<\/p>\n<p>P\u00f3ster <br \/>Datos de la empresa<br \/>HangZhou Gshine Machinery Co., Ltd. se encuentra en la ciudad de HangZhou, provincia de ZhangZhoug, cerca del puerto de ZheJiang. Somos una empresa l\u00edder especializada en el dise\u00f1o, la fabricaci\u00f3n y el mecanizado de productos. Nos hemos ganado el reconocimiento de nuestros clientes por nuestra alta calidad, precios competitivos y entregas puntuales. Nuestra f\u00e1brica cumple constantemente con las normas comerciales internacionales y se adhiere a la filosof\u00eda de \"Cumplimiento de contratos, transmisi\u00f3n sin fin de engranajes helicoidales de disco c\u00f3nico planetario de secuencia UDL con variador de velocidad y motor, compromiso, servicio de alta calidad, recompensa mutua y beneficio mutuo\" para establecer estrechas relaciones de cooperaci\u00f3n con la comunidad empresarial internacional, los c\u00edrculos industriales, cient\u00edficos y tecnol\u00f3gicos, y la comunidad financiera. A trav\u00e9s del comercio CZPT, conectamos a China con los mercados internacionales de forma m\u00e1s estrecha. Asumimos sinceramente la cooperaci\u00f3n con socios de todo el mundo e invitamos cordialmente a los clientes internacionales a visitar nuestra f\u00e1brica para una visita y negociaci\u00f3n. <\/p>\n<\/p>\n<p><table border=\"1\"><tr><td colspan=\"1\" rowspan=\"1\">Identificaci\u00f3n del producto<\/td><td colspan=\"3\" rowspan=\"1\">Pi\u00f1\u00f3n accionado por cadena de metal de aleaci\u00f3n de personalizaci\u00f3n no com\u00fan<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Material<\/td><td colspan=\"3\" rowspan=\"1\">Acero, Metal inoxidable, Aluminio, Cobre, Lat\u00f3n, Bronce o seg\u00fan necesidad del cliente <\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Est\u00e1ndar<\/td><td colspan=\"3\" rowspan=\"1\">Pi\u00f1\u00f3n de motor est\u00e1ndar y no com\u00fan \/ OEM y de 2 tiempos con llanta, componentes de repuesto para motosierra y desbrozadora ODM de acuerdo con los requisitos previos del cliente<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Procesamiento de producci\u00f3n<\/td><td colspan=\"3\" rowspan=\"1\">Aserrado, mecanizado, tallado, fresado, afeitado, rectificado, brochado, terapia de calor, terapia de suelos<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">M\u00e9todo de tratamiento de superficies<\/td><td colspan=\"3\" rowspan=\"1\">Anodizado duro o seg\u00fan los requisitos del cliente<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Tratamiento t\u00e9rmico<\/td><td colspan=\"3\" rowspan=\"1\">Carburaci\u00f3n, inducci\u00f3n, llama, nitruraci\u00f3n o seg\u00fan las necesidades del cliente. Componentes de bicicleta Bielas MTB Bicicleta cHangZhou Juego de bielas de aluminio de 170 mm con soporte de base<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Herramientas de prueba<\/td><td colspan=\"3\" rowspan=\"1\">Espectr\u00f3metro, detector de fallas ultras\u00f3nico, m\u00e1quina de ensayos de tracci\u00f3n, probador de dureza, dispositivo de medici\u00f3n de coordenadas, microscopio metal\u00fargico y otros recursos<\/td><\/tr><tr><td colspan=\"1\" rowspan=\"1\">Solicitud<\/td><td colspan=\"3\" rowspan=\"1\">Para caja de transferencia en maquinaria industrial mec\u00e1nica<\/td><\/tr><\/table>Mercanc\u00eda conectada <br \/>Embalaje y env\u00edo y entrega <\/p>\n<p>Preguntas frecuentes <br \/>P: \u00bfAceptan compras personalizadas?R: De hecho, generamos pedidos de acuerdo con el dibujo y la necesidad de los clientes.<\/p>\n<p>P: \u00bfQu\u00e9 frases de pago utiliza generalmente?R: Aceptamos este tipo de pago como: Western Union, T\/T, L\/C, etc.<\/p>\n<p>P: \u00bfCu\u00e1l es el plazo de entrega de sus productos? R: Se negocia seg\u00fan el monto de la compra.<\/p>\n<p>P: \u00bfPodemos visitar la unidad de fabricaci\u00f3n?R: Invitamos a todos los clientes a visitar nuestras instalaciones de fabricaci\u00f3n en cualquier momento.<\/p>\n<p>P: \u00bfPuedo tener la muestra?R: S\u00ed, 1 muestra es gratuita mientras que el consumidor requiere gastar el pago del servicio de mensajer\u00eda.<\/p>\n<p>P: \u00bfC\u00f3mo gestiona su organizaci\u00f3n el control de calidad? R: La calidad es fundamental en la vida diaria de una fundici\u00f3n. Controlamos estrictamente la calidad desde la materia prima hasta el embalaje.<\/p>\n<p>P: \u00bfEn cu\u00e1nto tiempo puedo responder las consultas?R: En 24 horas.<\/p>\n<\/p>\n<p>\n<h2>C\u00f3mo identificar una rueda dentada<\/h2>\n<p>Al elegir una rueda dentada, tiene varias opciones. Existen varios tipos, cada uno con caracter\u00edsticas \u00fanicas. En este art\u00edculo, explicaremos c\u00f3mo identificar ruedas dentadas y c\u00f3mo reemplazarlas si est\u00e1n desgastadas o da\u00f1adas.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/sprocket\/T-sprocket-3.webp\" alt=\"rueda de espigas\" width=\"800\" title=\"\"><\/p>\n<h2>comprar pi\u00f1ones<\/h2>\n<p>Al armar una bicicleta, los pi\u00f1ones son una parte importante de la transmisi\u00f3n. Desafortunadamente, son dif\u00edciles de encontrar fuera de lugares como CZPT. Afortunadamente, existen maneras f\u00e1ciles de encontrar el pi\u00f1\u00f3n adecuado para tu bicicleta.<br \/>Lo primero que debe considerar es qu\u00e9 tipo de pi\u00f1\u00f3n necesita. Elegir el pi\u00f1\u00f3n incorrecto puede da\u00f1ar su equipo o provocar una falla prematura. Si bien existen pi\u00f1ones de diversos tama\u00f1os, existen algunas caracter\u00edsticas clave que pueden ayudarle a encontrar el adecuado.<br \/>Hay dos tipos b\u00e1sicos de pi\u00f1ones. Puedes elegir uno de acero o aluminio, o una combinaci\u00f3n de ambos. La mayor\u00eda de los pi\u00f1ones son de acero, pero tambi\u00e9n hay pi\u00f1ones de aluminio nuevos que son similares al acero y duran tanto como este. Independientemente del material que elijas, es importante elegir un fabricante de confianza con mantenimiento regular.<br \/>Comprar pi\u00f1ones compatibles con la cadena es otra forma de garantizar una instalaci\u00f3n correcta. La cadena pasa por los pi\u00f1ones miles de veces por minuto, por lo que los dientes se desgastan con el tiempo. Un mantenimiento deficiente de los pi\u00f1ones tambi\u00e9n puede provocar dientes de gancho, lo que har\u00e1 que la cadena se estire hasta el punto de que ya no se pueda ajustar.<\/p>\n<h2>Identificar pi\u00f1ones<\/h2>\n<p>Una de las piezas m\u00e1s comunes de la bicicleta es el pi\u00f1\u00f3n, que se identifica por su anchura y n\u00famero de dientes. Un pi\u00f1\u00f3n simple tiene un diente a lo largo de su circunferencia, mientras que un pi\u00f1\u00f3n doble tiene dos filas de dientes. Los pi\u00f1ones tambi\u00e9n se conocen con diferentes nombres, como simples, dobles, triples y cu\u00e1druples.<br \/>Las ruedas dentadas de rodillos son otro tipo de rueda dentada. Se desplazan a lo largo de una cadena de rodillos conectados por pasadores. Se encajan en el espacio entre los rodillos de la cadena para transferir energ\u00eda cin\u00e9tica. Existen dos tipos b\u00e1sicos de ruedas dentadas de rodillos: de paso simple y de paso doble. Las ruedas dentadas de paso simple son peque\u00f1as y se ajustan perfectamente al equipo, mientras que las de paso doble son m\u00e1s grandes y requieren mayor grosor para soportar el peso.<br \/>Revisar un pi\u00f1\u00f3n es f\u00e1cil si sabes contar los dientes. Un calibrador simple te permitir\u00e1 encontrar f\u00e1cilmente pi\u00f1ones con dientes desgastados. Los calibradores tambi\u00e9n permiten medir el orificio del pi\u00f1\u00f3n, es decir, su di\u00e1metro interior.<br \/>Otra forma de saber si un pi\u00f1\u00f3n est\u00e1 desgastado es inspeccionarlo visualmente. Los pi\u00f1ones desgastados pueden hacer que la cadena rebote, lo que aumenta la presi\u00f3n sobre los rodamientos y acelera el desgaste. Tambi\u00e9n es importante comprobar la alineaci\u00f3n de los pi\u00f1ones. Si est\u00e1n descentrados, probablemente sea necesario cambiar la cadena.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/sprocket\/C-sprocket-3.webp\" alt=\"rueda de espigas\" width=\"800\" title=\"\"><\/p>\n<h2>Reemplazar la rueda dentada<\/h2>\n<p>Si quieres mantener tu bicicleta, es recomendable cambiar la cadena y los pi\u00f1ones con regularidad. Si no lo haces, podr\u00edas tener un problema que solo empeorar\u00e1. Las cadenas desgastadas tambi\u00e9n pueden hacer ruido, as\u00ed que conviene revisarlas con regularidad. Adem\u00e1s, debes lubricarlas y apretarlas con regularidad, especialmente cuando alcancen su kilometraje m\u00e1ximo.<br \/>Primero, debe determinar el tama\u00f1o de la cadena. Generalmente, lo encontrar\u00e1 en el manual. Los tama\u00f1os comunes son 520, 525 y 530. El primer n\u00famero se refiere al paso de la cadena, que es la distancia entre los remaches, mientras que el segundo se refiere al ancho del pi\u00f1\u00f3n. Por ejemplo, un pi\u00f1\u00f3n de 20 dientes mide 6,35 cm de ancho.<br \/>Reemplazar un pi\u00f1\u00f3n es un proceso relativamente sencillo. Aseg\u00farate de limpiar la bicicleta y aplicar grasa para rodamientos de rueda antes de comenzar. A continuaci\u00f3n, retira la cadena vieja de la rueda trasera. Algunas bicicletas pueden tener horquillas o paneles laterales que deben desmontarse. Un destornillador plano es una buena soluci\u00f3n para este problema. Tambi\u00e9n puedes usar la herramienta para eslabones rotos para retirar eslabones partidos.<br \/>Tambi\u00e9n puedes instalar pi\u00f1ones nuevos en tu bicicleta. Despu\u00e9s de retirar el viejo, aseg\u00farate de seguir las instrucciones del fabricante sobre el tama\u00f1o de la cadena y el pi\u00f1\u00f3n. Tambi\u00e9n debes apretar la tuerca del pi\u00f1\u00f3n seg\u00fan el par de apriete indicado por el fabricante. Una vez hecho esto, comprueba la tensi\u00f3n de la cadena para asegurarte de que no est\u00e9 ni demasiado floja ni demasiado apretada.<\/p>\n<h2>Reemplazar cadenas desgastadas<\/h2>\n<p>Para evitar da\u00f1os en la cadena, es necesario cambiarla regularmente. Es propensa al desgaste, pero puedes prolongar su vida \u00fatil con unos sencillos pasos. Uno de ellos es levantar la rueda trasera para poder pasar la cadena nueva por el desviador trasero. Esto facilitar\u00e1 la tarea, ya que la bicicleta no estar\u00e1 tirada en el suelo. Si no tienes portabicicletas, puedes usar bloques de hormig\u00f3n, madera o cajas para sujetarlo.<br \/>La se\u00f1al m\u00e1s obvia es que si la cadena rebota bajo carga, es necesario cambiar los platos. Usar un calibrador de cadena te permitir\u00e1 saber cu\u00e1ndo necesitas una cadena nueva. Los calibradores de cadena suelen tener dos caras y se utilizan para medir el desgaste de la cadena bajo una carga determinada. Puedes comprobar el calibrador coloc\u00e1ndolo en la cadena y asegur\u00e1ndote de que se hunda en ella.<br \/>Primero, debes quitar la cadena vieja. Algunas cadenas antiguas usan pasadores uniformes que puedes usar para reemplazarlas. Aseg\u00farate de conseguir una cadena del mismo largo que la anterior. Tambi\u00e9n, presta atenci\u00f3n al tipo de transmisi\u00f3n de tu bicicleta. Por ejemplo, si tiene desviador trasero, necesitar\u00e1s una cadena compatible con la misma transmisi\u00f3n.<\/p>\n<h2>Compruebe si la rueda dentada tiene \u00f3xido<\/h2>\n<p>Una de las mejores maneras de comprobar si tu bicicleta tiene \u00f3xido es buscar \u00f3xido superficial. Esta es la primera se\u00f1al de que el metal est\u00e1 empezando a oxidarse. Usar un cepillo de acero para eliminar el \u00f3xido superficial es recomendable, pero aseg\u00farate de usar gafas de seguridad. Tambi\u00e9n puedes limpiar los pi\u00f1ones con WD-40 o queroseno.<br \/>Otro indicador de que es necesario reemplazar un pi\u00f1\u00f3n es el desgaste excesivo. Esto puede deberse a objetos extra\u00f1os transportados por la cadena. Tambi\u00e9n puede ser necesario centrar la cadena y el pi\u00f1\u00f3n de arrastre, e instalar rodillos gu\u00eda. Otras se\u00f1ales de oxidaci\u00f3n del pi\u00f1\u00f3n incluyen la vibraci\u00f3n excesiva debido a orificios de eje mal mecanizados o una cadena doblada.<br \/>Tambi\u00e9n debe revisar si la cadena est\u00e1 torcida. De ser as\u00ed, podr\u00eda ser necesario reemplazarla. Adem\u00e1s, revise si hay manchas de \u00f3xido o exceso de grasa. Adem\u00e1s, debe revisar los pi\u00f1ones para asegurarse de que est\u00e9n correctamente alineados.<br \/>Adem\u00e1s del \u00f3xido, otra se\u00f1al de \u00f3xido es que la cadena se salga del pi\u00f1\u00f3n. Esto puede provocar que la cadena se atasque y que la bicicleta patine. Esta situaci\u00f3n tambi\u00e9n es peligrosa para usted y los dem\u00e1s conductores.<br \/><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/sprocket\/B-sprocket-3.webp\" alt=\"rueda de espigas\" width=\"800\" title=\"\"><\/p>\n<h2>Reemplazar pi\u00f1ones desgastados<\/h2>\n<p>Puedes reparar los engranajes de tu bicicleta reemplazando los pi\u00f1ones. Siempre revisa la cadena para detectar cualquier signo de desgaste. Si un pi\u00f1\u00f3n est\u00e1 desgastado, revisa los dientes, que suelen ser altos y ganchudos.<br \/>Si el pi\u00f1\u00f3n est\u00e1 curvado, torcido o irregular, est\u00e1 desgastado y debe reemplazarse. Si no se reemplazan, desgastar\u00e1n la cadena muy r\u00e1pidamente. Las cadenas deben reemplazarse en cuanto muestren signos de desgaste excesivo.<br \/>Para reemplazar un pi\u00f1\u00f3n desgastado, primero debe retirar el pi\u00f1\u00f3n trasero viejo. Para ello, afloje los tornillos que lo sujetan. Tambi\u00e9n debe limpiar la superficie del buje con lana de acero para reducir la corrosi\u00f3n y el desgaste.<br \/>Los pi\u00f1ones desgastados tienen dientes desgastados que impiden que la cadena patine. Esto puede provocar que la cadena se suba por los pi\u00f1ones y haga mucho ruido. Adem\u00e1s del ruido, las cadenas pueden atascarse en los pi\u00f1ones desgastados y da\u00f1arlos tanto a ellos como a la cadena. No espere a que la cadena pierda el control para arreglarla.<br \/>Tras retirar el pi\u00f1\u00f3n, se pueden sustituir el pi\u00f1\u00f3n trasero y el pi\u00f1\u00f3n de arrastre. Es importante comprobar la alineaci\u00f3n de los pi\u00f1ones, ya que una alineaci\u00f3n incorrecta puede provocar un desgaste prematuro de la cadena. Una alineaci\u00f3n correcta distribuir\u00e1 la carga uniformemente por todo el ancho de la cadena, prolongando su vida \u00fatil. Puede comprobar el pi\u00f1\u00f3n con una regla o una mira l\u00e1ser.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/sprocket\/sprocket-1.webp\" alt=\"Engranaje de transmisi\u00f3n diferencial c\u00f3nico de acero inoxidable con dientes personalizados de China, cadena de rodillos y ruedas dentadas, rueda dentada autom\u00e1tica\" title=\"\"><img decoding=\"async\" src=\"https:\/\/img.hzpt.com\/img\/sprocket\/sprocket-2.webp\" alt=\"Engranaje de transmisi\u00f3n diferencial c\u00f3nico de acero inoxidable con dientes personalizados de China, cadena de rodillos y ruedas dentadas, rueda dentada autom\u00e1tica\" title=\"\"><br \/>Editor por czh 13\/02\/2023<\/p>","protected":false},"excerpt":{"rendered":"<p>Industrias aplicables: Puntos de venta de materiales de construcci\u00f3n, planta de producci\u00f3n, minoristas de reparaci\u00f3n de equipos, obras de construcci\u00f3n, energ\u00eda y miner\u00eda. Material: Metal. Norma: ISO. Identificaci\u00f3n del producto: Pi\u00f1\u00f3n de cadena. Software: Equipo de transmisi\u00f3n. Tratamiento de la zona: Galvanizado. Detalles del embalaje: 1. Normalmente, embalaje neutro en el interior y embalaje de madera en el exterior. 2. Seg\u00fan las necesidades del cliente. 3. Puerto de carga: Hangzhou, Zhejiang u otros puertos seg\u00fan las necesidades del cliente. Puerto: [\u2026]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[161,354,1097,735,141,1303,1360,384,405,1361,1362,406,1120,1363,142,143,144,1019,145,1021,190,191,863,1026,1364,5,28,1219,1365,31,215,99,410,1121,32,1366,36,37,12,385,147,1358,40,1367,13,1359,49,1143,460,1368,152,1320,1313,1032,1369,1370,1371,1145,465,1372,153,1323,1110,1226,1106,154,155,1035,1327,1111,1373,7,386,1328,172,195,15,1037,83,233,1329,1112,1330,419,1374,813,469,466,157,1113,19,89,10,196,1375,1376,130,1248,131,489,92,1109,93],"class_list":["post-757","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-auto-gear","tag-auto-transmission-gear","tag-bore-roller-chain-sprocket","tag-bore-sprocket","tag-chain","tag-chain-and-drive","tag-chain-and-gear-drive","tag-chain-and-sprocket","tag-chain-drive","tag-chain-drive-differential","tag-chain-drive-gear","tag-chain-drive-sprocket","tag-chain-drive-sprockets","tag-chain-drive-transmission","tag-chain-gear","tag-chain-roller","tag-chain-roller-chain","tag-chain-roller-sprocket","tag-chain-sprocket","tag-chain-sprocket-roller","tag-chain-transmission","tag-chain-wheel-sprocket","tag-china-chain","tag-china-roller-chain","tag-china-roller-chain-drive","tag-china-sprocket","tag-custom-gear","tag-custom-roller-chain","tag-custom-roller-chain-sprockets","tag-custom-sprocket","tag-custom-sprockets","tag-differential-gear","tag-drive-chain","tag-drive-chain-sprockets","tag-drive-gear","tag-drive-roller-chain","tag-drive-sprocket","tag-drive-sprocket-wheel","tag-gear","tag-gear-and-chain","tag-gear-chain","tag-gear-custom","tag-gear-drive","tag-gear-drive-chain","tag-gear-sprocket","tag-gear-transmission","tag-gear-wheel","tag-idler-roller-chain","tag-idler-sprocket","tag-idler-sprockets-roller-chain","tag-roller-chain","tag-roller-chain-and-sprocket","tag-roller-chain-and-sprockets","tag-roller-chain-chain","tag-roller-chain-drive","tag-roller-chain-drive-sprockets","tag-roller-chain-gear","tag-roller-chain-idler","tag-roller-chain-idler-sprocket","tag-roller-chain-idler-wheel","tag-roller-chain-sprocket","tag-roller-chain-sprockets","tag-roller-chain-stainless-steel","tag-roller-chain-transmission","tag-roller-chain-wheel","tag-roller-gear","tag-roller-sprocket","tag-roller-sprocket-chain","tag-roller-sprockets-chain","tag-roller-steel-chain","tag-roller-transmission-chain-drive","tag-sprocket","tag-sprocket-and-chain","tag-sprocket-and-roller-chain","tag-sprocket-auto","tag-sprocket-chain-wheel","tag-sprocket-gear","tag-sprocket-roller-chain","tag-sprocket-wheel","tag-sprockets-chain","tag-sprockets-roller-chain","tag-stainless-roller-chain","tag-stainless-roller-chain-sprockets","tag-stainless-steel-chain","tag-stainless-steel-drive-chain","tag-stainless-steel-idler-sprocket","tag-stainless-steel-roller-chain","tag-stainless-steel-sprockets","tag-steel-chain","tag-steel-roller-chain","tag-steel-sprocket","tag-steel-sprocket-wheel","tag-teeth-sprocket","tag-transmission-chain","tag-transmission-chain-drive","tag-transmission-drive-roller-chain","tag-transmission-gear","tag-transmission-roller-chain","tag-transmission-sprocket","tag-wheel-and-sprocket","tag-wheel-gear","tag-wheel-roller-chain","tag-wheel-sprocket"],"_links":{"self":[{"href":"https:\/\/sprocketgear.top\/es\/wp-json\/wp\/v2\/posts\/757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sprocketgear.top\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sprocketgear.top\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sprocketgear.top\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sprocketgear.top\/es\/wp-json\/wp\/v2\/comments?post=757"}],"version-history":[{"count":0,"href":"https:\/\/sprocketgear.top\/es\/wp-json\/wp\/v2\/posts\/757\/revisions"}],"wp:attachment":[{"href":"https:\/\/sprocketgear.top\/es\/wp-json\/wp\/v2\/media?parent=757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sprocketgear.top\/es\/wp-json\/wp\/v2\/categories?post=757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sprocketgear.top\/es\/wp-json\/wp\/v2\/tags?post=757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}